{"id":7018,"date":"2023-02-24T12:08:54","date_gmt":"2023-02-24T12:08:54","guid":{"rendered":"https:\/\/www.mixlifeweb.com\/cimrbse\/?p=7018"},"modified":"2023-02-24T12:11:14","modified_gmt":"2023-02-24T12:11:14","slug":"abeirar-04-de-marco-conservacao-e-economia-baseada-na-natureza","status":"publish","type":"post","link":"https:\/\/www.mixlifeweb.com\/cimrbse\/comunicacao\/abeirar-04-de-marco-conservacao-e-economia-baseada-na-natureza\/","title":{"rendered":"aBEIRAr &#8211; 04 de mar\u00e7o &#8211; Conserva\u00e7\u00e3o e Economia Baseada na Natureza"},"content":{"rendered":"\n<p> <\/p>\n\n\n\n<p>04.03.2023 | Pinhel<\/p>\n\n\n\n<p>Neste evento vamos ter oportunidade de conhecer a Rede C\u00f4a Selvagem e perceber como a conserva\u00e7\u00e3o da natureza e a economia podem beneficiar-se mutuamente.<\/p>\n\n\n\n<p>Sobre a Rewilding: A Rewilding Portugal promove a Rede C\u00f4a Selvagem para dinamizar o turismo de natureza e produ\u00e7\u00e3o de produtos locais e regionais derivados de pr\u00e1ticas sustent\u00e1veis para fortalecer uma economia baseada na natureza no Grande Vale do C\u00f4a.<\/p>\n\n\n\n<p>O aBEIRAr \u00e9 uma Parceria de Ci\u00eancia Cidad\u00e3 para a Valoriza\u00e7\u00e3o do Territ\u00f3rio.<\/p>\n\n\n\n<p>Esta iniciativa tem como miss\u00e3o potenciar o envolvimento e a participa\u00e7\u00e3o c\u00edvica com a ci\u00eancia, promover o di\u00e1logo entre cientistas e cidad\u00e3os\/\u00e3s e despertar o interesse da comunidade na<\/p>\n\n\n\n<p>constru\u00e7\u00e3o de conhecimento e valoriza\u00e7\u00e3o do territ\u00f3rio. Nasce do cruzar de objetivos comuns entre a Rede Intermunicipal de Bibliotecas das Beiras e Serra da Estrela da CIMBSE, a Plataforma de Ci\u00eancia Aberta \u2013 Munic\u00edpio de Figueira de Castelo Rodrigo, o Estrela Geopark Mundial da UNESCO e a Universidade da Beira Interior.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2023\/02\/aBEIRAr-Pinhel-Redes-Sociais.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1030\" height=\"1030\" src=\"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2023\/02\/aBEIRAr-Pinhel-Redes-Sociais-1030x1030.png\" alt=\"\" class=\"wp-image-7019\" srcset=\"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2023\/02\/aBEIRAr-Pinhel-Redes-Sociais-1030x1030.png 1030w, https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2023\/02\/aBEIRAr-Pinhel-Redes-Sociais-300x300.png 300w, https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2023\/02\/aBEIRAr-Pinhel-Redes-Sociais-80x80.png 80w, https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2023\/02\/aBEIRAr-Pinhel-Redes-Sociais-768x768.png 768w, https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2023\/02\/aBEIRAr-Pinhel-Redes-Sociais-36x36.png 36w, https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2023\/02\/aBEIRAr-Pinhel-Redes-Sociais-180x180.png 180w, https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2023\/02\/aBEIRAr-Pinhel-Redes-Sociais.png 1500w\" sizes=\"auto, (max-width: 1030px) 100vw, 1030px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>04.03.2023 | Pinhel Neste evento vamos ter oportunidade de conhecer a Rede C\u00f4a Selvagem e perceber como a conserva\u00e7\u00e3o da natureza e a economia podem beneficiar-se mutuamente. Sobre a Rewilding: A Rewilding Portugal promove a Rede C\u00f4a Selvagem para dinamizar o turismo de natureza e produ\u00e7\u00e3o de produtos locais e regionais derivados de pr\u00e1ticas sustent\u00e1veis [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":7019,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,4],"tags":[206],"class_list":["post-7018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacao","category-noticias","tag-abeirar-ii"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/7018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/comments?post=7018"}],"version-history":[{"count":2,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/7018\/revisions"}],"predecessor-version":[{"id":7021,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/7018\/revisions\/7021"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media\/7019"}],"wp:attachment":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media?parent=7018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/categories?post=7018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/tags?post=7018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}