{"id":5927,"date":"2021-10-19T14:59:49","date_gmt":"2021-10-19T13:59:49","guid":{"rendered":"https:\/\/www.mixlifeweb.com\/cimrbse\/?p=5927"},"modified":"2024-07-04T11:46:24","modified_gmt":"2024-07-04T10:46:24","slug":"no-territorio-da-comunidade-intermunicipal-das-beiras-e-serra-da-estrela-estao-disponiveis-espacos-de-teletrabalho-coworking","status":"publish","type":"post","link":"https:\/\/www.mixlifeweb.com\/cimrbse\/comunicacao\/no-territorio-da-comunidade-intermunicipal-das-beiras-e-serra-da-estrela-estao-disponiveis-espacos-de-teletrabalho-coworking\/","title":{"rendered":"No territ\u00f3rio da Comunidade Intermunicipal das Beiras e Serra da Estrela est\u00e3o dispon\u00edveis espa\u00e7os de Teletrabalho\/Coworking"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2whwyf-d46460c1af86bed3b6701a9bf8f8239f\">\n.flex_column.av-2whwyf-d46460c1af86bed3b6701a9bf8f8239f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-2whwyf-d46460c1af86bed3b6701a9bf8f8239f av_one_full  avia-builder-el-0  el_before_av_textblock  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kv6vkgii-d457455a61ed987f8fe9ccfe5365b6a1\">\n.avia-image-container.av-kv6vkgii-d457455a61ed987f8fe9ccfe5365b6a1 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-kv6vkgii-d457455a61ed987f8fe9ccfe5365b6a1 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-kv6vkgii-d457455a61ed987f8fe9ccfe5365b6a1 av-styling- avia-align-center  avia-builder-el-1  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-7937 avia-img-lazy-loading-not-7937 avia_image ' src=\"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2024\/07\/Mapa-Coworks-verdes-495x400.png\" alt='' title='Mapa Coworks verdes'  height=\"400\" width=\"495\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><\/div><section  class='av_textblock_section av-kuy5myuy-e61a812bd1824b7d169c146ea58f938e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><p>A Comunidade Intermunicipal das Beiras e Serra da Estrela (CIM-BSE) tem j\u00e1 instalados espa\u00e7os de teletrabalho e Coworking em 6 concelhos do territ\u00f3rio da regi\u00e3o das Beiras e Serra da Estrela protocolados com acordos de coopera\u00e7\u00e3o entre a Comunidade Intermunicipal das Beiras e Serra da Estrela (CIM-BSE), Comiss\u00e3o de Coordena\u00e7\u00e3o e Desenvolvimento Regional do Centro (CCDRC), o Minist\u00e9rio do Trabalho, Solidariedade e Seguran\u00e7a Social, Minist\u00e9rio da Coes\u00e3o Territorial e os seguintes Munic\u00edpios: Covilh\u00e3, Figueira de Castelo Rodrigo, Fund\u00e3o, Guarda, Pinhel e Sabugal, estando previsto o alargamento a todos os Munic\u00edpios que constituem a CIM-BSE, no pr\u00f3ximo ano.<\/p>\n<p>A medida tomada pelo Governo de forma a dinamizar os territ\u00f3rios do Interior e facilitar a fixa\u00e7\u00e3o e atra\u00e7\u00e3o de pessoas e empresas, permitiu atrav\u00e9s da assinatura de acordos de coopera\u00e7\u00e3o para a instala\u00e7\u00e3o de espa\u00e7os de teletrabalho\/coworking no Interior, do qual s\u00e3o parceiros a Comiss\u00e3o de Coordena\u00e7\u00e3o e Desenvolvimento Regional do Centro (CCDRC), o Instituto de Emprego e Forma\u00e7\u00e3o Profissional (IEFP) e a Comunidade Intermunicipal das Beiras e Serra da Estrela (CIM-BSE), a cria\u00e7\u00e3o destes espa\u00e7os.<br \/>\nOs espa\u00e7os de Teletrabalho e Coworking s\u00e3o assim disponibilizados pelas autarquias, equipados com computadores, impressoras e acesso \u00e0 Internet, sendo divididos em \u00e1reas de diferentes tipologias que contemplam zonas privadas para videochamadas, \u00e1reas para reuni\u00f5es e locais para a realiza\u00e7\u00e3o de apresenta\u00e7\u00f5es ou a\u00e7\u00f5es de forma\u00e7\u00e3o.<br \/>\nAs autarquias s\u00e3o respons\u00e1veis pela divulga\u00e7\u00e3o dos Espa\u00e7os atrav\u00e9s das respetivas p\u00e1ginas e redes sociais, permitindo a realiza\u00e7\u00e3o de visitas virtuais por parte de eventuais interessados, bem como toda a informa\u00e7\u00e3o relativa \u00e0s caracter\u00edsticas do espa\u00e7o, condi\u00e7\u00f5es de utiliza\u00e7\u00e3o, calend\u00e1rio anual, hor\u00e1rio de utiliza\u00e7\u00e3o e custo associado.<br \/>\nO teletrabalho e o coworking representam uma grande vantagem do ponto de vista da redu\u00e7\u00e3o da assimetria geogr\u00e1fica de ofertas profissionais, democratizando as oportunidades entre as regi\u00f5es de elevada densidade populacional e as de menor densidade.<\/p>\n<p>Mais informa\u00e7\u00f5es dispon\u00edveis <a href=\"https:\/\/www.mixlifeweb.com\/cimrbse\/empreendedorismo\/espacos-de-teletrabalho-ou-coworking-no-territorio-do-interior\/\">AQUI<\/a><\/p>\n<\/div><\/section><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":14,"featured_media":5894,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,4],"tags":[171],"class_list":["post-5927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacao","category-noticias","tag-teletrabalho-coworking"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/5927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/comments?post=5927"}],"version-history":[{"count":7,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/5927\/revisions"}],"predecessor-version":[{"id":7961,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/5927\/revisions\/7961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media\/5894"}],"wp:attachment":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media?parent=5927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/categories?post=5927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/tags?post=5927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}