{"id":4610,"date":"2021-03-03T15:00:13","date_gmt":"2021-03-03T15:00:13","guid":{"rendered":"https:\/\/www.mixlifeweb.com\/cimrbse\/?p=4610"},"modified":"2021-03-03T19:53:37","modified_gmt":"2021-03-03T19:53:37","slug":"a-comunidade-intermunicipal-das-beiras-e-serra-da-estrela-entregou-hoje-15-unidades-moveis-de-saude-ums-aos-15-municipios-que-a-integram","status":"publish","type":"post","link":"https:\/\/www.mixlifeweb.com\/cimrbse\/comunicacao\/a-comunidade-intermunicipal-das-beiras-e-serra-da-estrela-entregou-hoje-15-unidades-moveis-de-saude-ums-aos-15-municipios-que-a-integram\/","title":{"rendered":"A Comunidade Intermunicipal das Beiras e Serra da Estrela, entregou hoje 15 Unidades M\u00f3veis de Sa\u00fade (UMS) aos 15 Munic\u00edpios que a integram"},"content":{"rendered":"<p>A cerim\u00f3nia de entrega das chaves das Unidades M\u00f3veis de Sa\u00fade aos presidentes dos Munic\u00edpios que integram a CIM-BSE, decorreu no Grande Audit\u00f3rio do Teatro Municipal da Guarda pelas 10:30 e contou com a presen\u00e7a da Ministra da Coes\u00e3o Territorial, Ana Abrunhosa, do Secret\u00e1rio de Estado Adjunto da Sa\u00fade, Ant\u00f3nio Lacerda Sales, do Secret\u00e1rio de Estado da Juventude e do Desporto, Jo\u00e3o Paulo Rebelo na qualidade de Coordenador de Combate ao novo coronav\u00edrus na zona Centro, do Presidente da CIM-BSE , Lu\u00eds Tadeu, a Presidente da CCDRC, Isabel Damasceno, a Presidente da ARS Centro, Rosa Marques e o Presidente da ULS Guarda, Jo\u00e3o Barranca.<\/p>\n<p>A sess\u00e3o iniciou com a interven\u00e7\u00e3o do Presidente da CIM-BSE, Lu\u00eds Tadeu que referiu \u201cPretendemos com estas viaturas que hoje entregamos, refor\u00e7ar o empenhamento e acompanhamento de proximidade das nossas popula\u00e7\u00f5es, permitindo desta forma refor\u00e7ar os servi\u00e7os de sa\u00fade e de apoio social com qualidade e com acesso muitas vezes limitado\u201d.<\/p>\n<p>As viaturas visam assegurar uma maior acessibilidade e qualidade na presta\u00e7\u00e3o de sa\u00fade prim\u00e1ria \u00e0 popula\u00e7\u00e3o dos respetivos Concelhos da CIM-BSE contribuindo para a redu\u00e7\u00e3o das desigualdades e exclus\u00e3o social, com o objetivo de proporcionar a estes um melhor acesso \u00e0 presta\u00e7\u00e3o de cuidados de sa\u00fade, nomeadamente em termos de cuidados de sa\u00fade domicili\u00e1rios, doen\u00e7a mental e cuidados paliativos.<\/p>\n<p>As Unidades M\u00f3veis de Sa\u00fade (UMS), constituem um recurso de excel\u00eancia, permitindo uma melhor interven\u00e7\u00e3o na avalia\u00e7\u00e3o da condi\u00e7\u00e3o de sa\u00fade da popula\u00e7\u00e3o, alertando para a import\u00e2ncia da preven\u00e7\u00e3o, do diagn\u00f3stico precoce e da ado\u00e7\u00e3o de estilos de vida e comportamentos saud\u00e1veis.<\/p>\n<p>Jo\u00e3o Paulo Rebelo, Secret\u00e1rio de Estado da Juventude de do Desporto, na qualidade de Coordenador de Combate ao novo coronav\u00edrus na zona Centro adiantou ainda que \u201cAs viaturas entregues consubstanciam mais uma ajuda evidente que os Munic\u00edpios d\u00e3o de grande proximidade \u00e9 mais um refor\u00e7o e elo aos cidad\u00e3os\u201d<\/p>\n<p>O Secret\u00e1rio de Estado Adjunto da Sa\u00fade, Ant\u00f3nio Lacerda Sales, dirigiu as primeiras palavras \u00e0 CIM-BSE reconhecendo publicamente \u201co inestim\u00e1vel contributo que est\u00e3o a dar ao nosso pa\u00eds sobretudo a esta regi\u00e3o, a defini\u00e7\u00e3o de pol\u00edticas p\u00fablicas\u201d referiu ainda \u201ctratar-se de \u201cum reconhecimento justo aos autarcas da regi\u00e3o que constituem um exemplo a seguir\u201d.<\/p>\n<p>A execu\u00e7\u00e3o deste projeto e a sua correta implementa\u00e7\u00e3o no terreno s\u00f3 \u00e9 poss\u00edvel atrav\u00e9s do compromisso da Comunidade Intermunicipal das Beiras e Serra da Estrela, a Administra\u00e7\u00e3o Regional de Sa\u00fade do Centro, a Unidade local de Sa\u00fade e cada um dos Munic\u00edpios que integram esta Comunidade, que assinaram um protocolo de colabora\u00e7\u00e3o para a implementa\u00e7\u00e3o das Unidades M\u00f3veis de Sa\u00fade, e um protocolo operacional de utiliza\u00e7\u00e3o destas unidades.<\/p>\n<p>O encerramento da cerim\u00f3nia teve a interven\u00e7\u00e3o da Ministra da Coes\u00e3o Territorial, Ana Abrunhosa, que evidenciou o exemplo de coes\u00e3o, pela decis\u00e3o que tomaram em conjunto, num projeto conjunto, com a ARS Centro, a ULS, e com a CCDRC para atingir o objetivo comum.<\/p>\n<p>Salienta que \u201cCoes\u00e3o tamb\u00e9m \u00e9 isto, utilizar os fundos comunit\u00e1rios ao servi\u00e7o destes projetos\u201d. \u201cA obriga\u00e7\u00e3o do Estado \u00e9 aproximar os servi\u00e7os do estado \u00e0s nossas Comunidades e lev\u00e1-los inclusivamente \u00e0 sua porta\u201d acrescentou ainda que \u201cTemos solu\u00e7\u00f5es hoje nos ajudam a cumprir este objetivo, e uma delas s\u00e3o as Unidades M\u00f3veis de Sa\u00fade\u201d, \u201c\u00c9 fundamental uma atua\u00e7\u00e3o precoce atempada, reduzindo gradualmente interven\u00e7\u00f5es de emerg\u00eancia\u201d, referiu a Ministra.<\/p>\n<p>A candidatura prevista no pacto da CIM-BSE na PI 9.7 (Investimentos na sa\u00fade e nas infraestruturas sociais) feita no \u00e2mbito de uma candidatura financiada pelo Programa Operacional Centro 2020, designada \u201cUnidades M\u00f3veis de Sa\u00fade para o territ\u00f3rio CIM-BSE\u201d, contou com um investimento de 612.079 euros e uma comparticipa\u00e7\u00e3o de 85% pelo FEDER (Fundo Europeu de Desenvolvimento Regional).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A cerim\u00f3nia de entrega das chaves das Unidades M\u00f3veis de Sa\u00fade aos presidentes dos Munic\u00edpios que integram a CIM-BSE, decorreu no Grande Audit\u00f3rio do Teatro Municipal da Guarda pelas 10:30 e contou com a presen\u00e7a da Ministra da Coes\u00e3o Territorial, Ana Abrunhosa, do Secret\u00e1rio de Estado Adjunto da Sa\u00fade, Ant\u00f3nio Lacerda Sales, do Secret\u00e1rio de [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":4611,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,4],"tags":[],"class_list":["post-4610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacao","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/4610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/comments?post=4610"}],"version-history":[{"count":4,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/4610\/revisions"}],"predecessor-version":[{"id":4776,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/4610\/revisions\/4776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media\/4611"}],"wp:attachment":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media?parent=4610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/categories?post=4610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/tags?post=4610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}