{"id":4114,"date":"2020-06-09T15:20:07","date_gmt":"2020-06-09T14:20:07","guid":{"rendered":"https:\/\/www.mixlifeweb.com\/cimrbse\/?p=4114"},"modified":"2020-06-10T15:24:04","modified_gmt":"2020-06-10T14:24:04","slug":"conselho-intermunicipal-delibera-sobre-indicacao-de-personalidade-para-integrar-conselho-de-administracao-da-unidade-local-de-saude-da-guarda-e-p-e","status":"publish","type":"post","link":"https:\/\/www.mixlifeweb.com\/cimrbse\/comunicacao\/conselho-intermunicipal-delibera-sobre-indicacao-de-personalidade-para-integrar-conselho-de-administracao-da-unidade-local-de-saude-da-guarda-e-p-e\/","title":{"rendered":"Conselho Intermunicipal delibera sobre indica\u00e7\u00e3o de personalidade para integrar Conselho de Administra\u00e7\u00e3o da Unidade Local de Sa\u00fade da Guarda, E.P.E."},"content":{"rendered":"<p>O Conselho Intermunicipal da Comunidade Intermunicipal das Beiras e Serra da Estrela (CIMBSE) deliberou, na sua reuni\u00e3o de 9 de junho, realizada na C\u00e2mara Municipal da Guarda, indicar para integrar o Conselho de Administra\u00e7\u00e3o da Unidade Local de Sa\u00fade da Guarda, E. P. E., o Sr. Eng.\u00ba Jos\u00e9 Francisco Gomes Monteiro.<br \/>\nDe acordo com o disposto no artigo 6\u00ba do Estatutos das Unidades Locais de Sa\u00fade, E.P.E., constantes do Anexo lI do Decreto-Lei n.\u00ba 18\/2017, de 10 de fevereiro, a personalidade indicada pela Comunidade Intermunicipal ocupar\u00e1 o lugar de vogal executivo no Conselho de Administra\u00e7\u00e3o da ULS.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Intermunicipal da Comunidade Intermunicipal das Beiras e Serra da Estrela (CIMBSE) deliberou, na sua reuni\u00e3o de 9 de junho, realizada na C\u00e2mara Municipal da Guarda, indicar para integrar o Conselho de Administra\u00e7\u00e3o da Unidade Local de Sa\u00fade da Guarda, E. P. E., o Sr. Eng.\u00ba Jos\u00e9 Francisco Gomes Monteiro. De acordo com o [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":3939,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,4],"tags":[],"class_list":["post-4114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacao","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/4114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/comments?post=4114"}],"version-history":[{"count":2,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/4114\/revisions"}],"predecessor-version":[{"id":4117,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/4114\/revisions\/4117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media\/3939"}],"wp:attachment":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media?parent=4114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/categories?post=4114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/tags?post=4114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}