{"id":3618,"date":"2020-01-28T15:45:03","date_gmt":"2020-01-28T15:45:03","guid":{"rendered":"https:\/\/www.mixlifeweb.com\/cimrbse\/?p=3618"},"modified":"2020-01-28T15:49:06","modified_gmt":"2020-01-28T15:49:06","slug":"ministra-da-modernizacao-do-estado-e-da-administracao-publica-e-secretario-de-estado-da-descentralizacao-e-da-administracao-local-reunem-na-sede-da-cimbse","status":"publish","type":"post","link":"https:\/\/www.mixlifeweb.com\/cimrbse\/comunicacao\/ministra-da-modernizacao-do-estado-e-da-administracao-publica-e-secretario-de-estado-da-descentralizacao-e-da-administracao-local-reunem-na-sede-da-cimbse\/","title":{"rendered":"Ministra da Moderniza\u00e7\u00e3o do Estado e da Administra\u00e7\u00e3o P\u00fablica e Secret\u00e1rio de Estado da Descentraliza\u00e7\u00e3o e da Administra\u00e7\u00e3o Local re\u00fanem na sede da CIMBSE"},"content":{"rendered":"<p>Decorreu esta manh\u00e3, na sede da Comunidade Intermunicipal das Beiras e Serra da Estrela, a reuni\u00e3o de trabalho do Conselho Intermunicipal que contou com a presen\u00e7a da Ministra da Moderniza\u00e7\u00e3o do Estado e da Administra\u00e7\u00e3o P\u00fablica, Alexandra Leit\u00e3o, e com o Secret\u00e1rio de Estado da Descentraliza\u00e7\u00e3o e da Administra\u00e7\u00e3o Local, Jorge Botelho.<br \/>\nEsta visita teve como objetivo o levantamento de necessidades, no \u00e2mbito do processo de descentraliza\u00e7\u00e3o, promovendo um trabalho colaborativo e de proximidade entre o Estado Central e o Poder Local.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decorreu esta manh\u00e3, na sede da Comunidade Intermunicipal das Beiras e Serra da Estrela, a reuni\u00e3o de trabalho do Conselho Intermunicipal que contou com a presen\u00e7a da Ministra da Moderniza\u00e7\u00e3o do Estado e da Administra\u00e7\u00e3o P\u00fablica, Alexandra Leit\u00e3o, e com o Secret\u00e1rio de Estado da Descentraliza\u00e7\u00e3o e da Administra\u00e7\u00e3o Local, Jorge Botelho. Esta visita teve [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":3619,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,4],"tags":[],"class_list":["post-3618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacao","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/3618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/comments?post=3618"}],"version-history":[{"count":1,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/3618\/revisions"}],"predecessor-version":[{"id":3620,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/3618\/revisions\/3620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media\/3619"}],"wp:attachment":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media?parent=3618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/categories?post=3618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/tags?post=3618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}