{"id":3002,"date":"2019-07-29T09:59:27","date_gmt":"2019-07-29T09:59:27","guid":{"rendered":"https:\/\/www.mixlifeweb.com\/cimrbse\/?p=3002"},"modified":"2019-07-29T09:59:27","modified_gmt":"2019-07-29T09:59:27","slug":"brigada-de-sapadores-da-cimbse-realiza-trabalhos-de-silvicultura","status":"publish","type":"post","link":"https:\/\/www.mixlifeweb.com\/cimrbse\/comunicacao\/brigada-de-sapadores-da-cimbse-realiza-trabalhos-de-silvicultura\/","title":{"rendered":"Brigada de Sapadores da CIMBSE realiza trabalhos de Silvicultura"},"content":{"rendered":"<p>Cerca de 108 hectares de Faixas de Gest\u00e3o de Combust\u00edvel foi a \u00e1rea limpa desde mar\u00e7o pela Brigada de Sapadores Florestais ao servi\u00e7o da Comunidade Intermunicipal das Beiras e Serra da Estrela.<\/p>\n<p>Esta Brigada constitu\u00edda por tr\u00eas equipas instaladas nos concelhos de Belmonte, Pinhel e Gouveia, apoiada por 15 homens e tr\u00eas viaturas florestais, opera nos 15 munic\u00edpios que integram a CIMBSE.<\/p>\n<p>Ap\u00f3s forma\u00e7\u00e3o t\u00e9cnica espec\u00edfica, a equipa de Sapadores Florestais composta por 14 Sapadores Florestais e 1 T\u00e9cnico Florestal com forma\u00e7\u00e3o em silvicultura e credenciado em fogo controlado, tem vindo a realizar trabalhos de limpeza de gest\u00e3o de combust\u00edvel. S\u00e3o respons\u00e1veis pela realiza\u00e7\u00e3o de a\u00e7\u00f5es de silvicultura preventiva no \u00e2mbito dos inc\u00eandios florestais (na vertente da gest\u00e3o de combust\u00edvel florestal), com recurso a t\u00e9cnicas manuais, moto manuais e pelo uso de fogo controlado.<\/p>\n<p>As \u00e1reas intervencionadas at\u00e9 ao momento pertencem aos concelhos de Almeida, Celorico da Beira, Covilh\u00e3, Figueira de Castelo Rodrigo, Fund\u00e3o, Gouveia, Guarda, Manteigas, Pinhel, Sabugal, Seia e Trancoso, estando neste momento a efetuar trabalhos para o ICNF, mais concretamente na instala\u00e7\u00e3o e manuten\u00e7\u00e3o da rede prim\u00e1ria de defesa da floresta contra inc\u00eandios.<\/p>\n<p>Esta Brigada de Sapadores Florestais nasceu na sequ\u00eancia do estabelecido na Estrat\u00e9gia Nacional para as Florestas, contribuindo assim para a diminui\u00e7\u00e3o do risco de inc\u00eandio no territ\u00f3rio CIMBSE. Tem como principais objetivos aumentar a \u00e1rea de interven\u00e7\u00e3o com a\u00e7\u00f5es de redu\u00e7\u00e3o de combust\u00edvel e a resili\u00eancia do seu territ\u00f3rio aos inc\u00eandios, uma atua\u00e7\u00e3o em conson\u00e2ncia com os objetivos definidos na Estrat\u00e9gia Nacional para as Florestas e no Plano Nacional de Defesa da Floresta Contra Inc\u00eandios.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cerca de 108 hectares de Faixas de Gest\u00e3o de Combust\u00edvel foi a \u00e1rea limpa desde mar\u00e7o pela Brigada de Sapadores Florestais ao servi\u00e7o da Comunidade Intermunicipal das Beiras e Serra da Estrela. Esta Brigada constitu\u00edda por tr\u00eas equipas instaladas nos concelhos de Belmonte, Pinhel e Gouveia, apoiada por 15 homens e tr\u00eas viaturas florestais, opera [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":3003,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,4],"tags":[118],"class_list":["post-3002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacao","category-noticias","tag-sapadores"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/3002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/comments?post=3002"}],"version-history":[{"count":2,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/3002\/revisions"}],"predecessor-version":[{"id":3012,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/3002\/revisions\/3012"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media\/3003"}],"wp:attachment":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media?parent=3002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/categories?post=3002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/tags?post=3002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}