{"id":2195,"date":"2018-05-28T15:53:06","date_gmt":"2018-05-28T15:53:06","guid":{"rendered":"https:\/\/www.mixlifeweb.com\/cimrbse\/?p=2195"},"modified":"2018-05-28T15:58:09","modified_gmt":"2018-05-28T15:58:09","slug":"concurso-regional-de-ideias-de-negocio-nas-escolas-nas-beiras-e-serra-da-estrela","status":"publish","type":"post","link":"https:\/\/www.mixlifeweb.com\/cimrbse\/comunicacao\/concurso-regional-de-ideias-de-negocio-nas-escolas-nas-beiras-e-serra-da-estrela\/","title":{"rendered":"Concurso Regional de Ideias de Neg\u00f3cio nas Escolas nas Beiras e Serra da Estrela"},"content":{"rendered":"<p>O Concurso Regional de Ideias de Neg\u00f3cio nas Escolas ter\u00e1 este ano a sua final regional no territ\u00f3rio da <a href=\"https:\/\/www.mixlifeweb.com\/cimrbse\/\">Comunidade Intermunicipal das Beiras e Serra da Estrela (CIMBSE).<\/a> Esta iniciativa \u00e9 da tutela da <a href=\"http:\/\/www.ccdrc.pt\/\">Comiss\u00e3o de Coordena\u00e7\u00e3o e Desenvolvimento Regional do Centro (CCDRC)<\/a> e decorre em estreita colabora\u00e7\u00e3o com as Comunidades Intermunicipais (CIM) da Regi\u00e3o Centro. Neste sentido, visa a divulga\u00e7\u00e3o, est\u00edmulo e implementa\u00e7\u00e3o da cultura empreendedora na Regi\u00e3o Centro, junto da comunidade escolar.<\/p>\n<p>Na pr\u00f3xima quarta-feira, dia 30 de maio, realiza-se a sess\u00e3o intermunicipal, onde s\u00f3 participam as escolas da CIMBSE, no audit\u00f3rio da Escola Superior de Tecnologia e Gest\u00e3o, no<a href=\"http:\/\/www.ipg.pt\/website\/\"> Instituto Polit\u00e9cnico da Guarda (IPG)<\/a>, a partir das 09h30.<\/p>\n<p>O objetivo do concurso \u00e9 sensibilizar e motivar os jovens para a inova\u00e7\u00e3o e o empreendedorismo, promovendo a iniciativa e o dinamismo nas comunidades em que se inserem.<\/p>\n<p>Este ano, a final regional, que pretende ser um momento marcante, com a atribui\u00e7\u00e3o do t\u00edtulo \u201cAluno Empreendedor da Regi\u00e3o Centro 2018\u201d, decorrer\u00e1 no territ\u00f3rio da CIMBSE, realizando-se no dia 7 de junho, na Universidade da Beira Interior.<\/p>\n<p>Podem ser apresentadas ideias de neg\u00f3cio de qualquer \u00e1rea de atividade, devendo obedecer \u00e0s seguintes caracter\u00edsticas: \u201c\u00fateis e exequ\u00edveis; inovadoras, podendo dar origem ao aparecimento de um novo produto ou servi\u00e7o; consolidadas; originais (concebidas pelos candidatos) e economicamente vantajosas, apresentando potencial competitivo\u201d.<br \/>\nCada uma das oito comunidades intermunicipais, da Regi\u00e3o Centro, poder\u00e1 apresentar a concurso uma ideia de neg\u00f3cio, por si selecionada, concebida e apresentada pelos pr\u00f3prios alunos.<\/p>\n<p><strong>PROGRAMA<\/strong><br \/>\n9h30 \u2013 Sess\u00e3o de boas vindas<br \/>\n10h00 \u2013 Apresenta\u00e7\u00e3o das Ideias de neg\u00f3cio<br \/>\n12h00 \u2013 Momento musical<br \/>\n12h30 \u2013 Apresenta\u00e7\u00e3o das classifica\u00e7\u00f5es e entrega de pr\u00e9mios<br \/>\n13h00 &#8211; Almo\u00e7o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na pr\u00f3xima quarta-feira, dia 30 de maio, realiza-se a sess\u00e3o intermunicipal, no audit\u00f3rio da Escola Superior de Tecnologia e Gest\u00e3o, no Instituto Polit\u00e9cnico da Guarda, a partir das 09h30.<\/p>\n","protected":false},"author":14,"featured_media":2196,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,4],"tags":[69,63,68,64,66],"class_list":["post-2195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacao","category-noticias","tag-beiras-e-serra-da-estrela","tag-cimbse","tag-concurso-regional-de-ideias-de-negocio-nas-escolas","tag-guarda","tag-ipg"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/2195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/comments?post=2195"}],"version-history":[{"count":3,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/2195\/revisions"}],"predecessor-version":[{"id":2198,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/2195\/revisions\/2198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media\/2196"}],"wp:attachment":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media?parent=2195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/categories?post=2195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/tags?post=2195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}