{"id":98,"date":"2015-10-21T15:14:26","date_gmt":"2015-10-21T15:14:26","guid":{"rendered":"http:\/\/cimbse.pt\/?page_id=98"},"modified":"2015-10-21T15:19:01","modified_gmt":"2015-10-21T15:19:01","slug":"qren","status":"publish","type":"page","link":"https:\/\/www.mixlifeweb.com\/cimrbse\/projetos\/qren\/","title":{"rendered":"Qren"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_image-28e827e0981e017099633ac4a4bc351b\">\n.avia-image-container.av-av_image-28e827e0981e017099633ac4a4bc351b img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-av_image-28e827e0981e017099633ac4a4bc351b .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-av_image-28e827e0981e017099633ac4a4bc351b av-styling- avia-align-left  avia-builder-el-0  el_before_av_hr  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-100 avia-img-lazy-loading-not-100 avia_image ' src=\"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2015\/10\/qren-logo1-300x128.png\" alt='' title='qren-logo[1]'  height=\"128\" width=\"300\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2015\/10\/qren-logo1-300x128.png 300w, https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2015\/10\/qren-logo1-768x327.png 768w, https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2015\/10\/qren-logo1-1030x439.png 1030w, https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2015\/10\/qren-logo1-1500x640.png 1500w, https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2015\/10\/qren-logo1-705x301.png 705w, https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2015\/10\/qren-logo1-450x192.png 450w, https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2015\/10\/qren-logo1.png 1548w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/div><\/div>\n<div  class='hr av-av_hr-dcd2069817a0e3d34ae04cad8f3443c7 hr-default  avia-builder-el-1  el_after_av_image  el_before_av_toggle_container '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<div  class='togglecontainer av-av_toggle_container-8e0c6e39d39b619a829887bd54fff3ed  avia-builder-el-2  el_after_av_hr  avia-builder-el-last  toggle_close_all' >\n<section class='av_toggle_section av-av_toggle-c3320f2427c0d1489319a4a4e27b8616'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Todos} \"  ><p id='toggle-toggle-id-1' data-fake-id='#toggle-id-1' class='toggler  av-title-above '  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-1' data-slide-speed=\"200\" data-title=\"QREN 2013\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: QREN 2013\" data-aria_expanded=\"Click to collapse: QREN 2013\">QREN 2013<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-1' aria-labelledby='toggle-toggle-id-1' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color '  itemprop=\"text\" ><p>Em desenvolvimento&#8230;<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-av_toggle-0df67419394ba5fd8f0d3d48b042c5be'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Todos} \"  ><p id='toggle-toggle-id-2' data-fake-id='#toggle-id-2' class='toggler  av-title-above '  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-2' data-slide-speed=\"200\" data-title=\"QREN 2014\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: QREN 2014\" data-aria_expanded=\"Click to collapse: QREN 2014\">QREN 2014<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-2' aria-labelledby='toggle-toggle-id-2' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color '  itemprop=\"text\" ><p>Em desenvolvimento<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-av_toggle-7618408427324adadc172eaed0712f53'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Todos} \"  ><p id='toggle-toggle-id-3' data-fake-id='#toggle-id-3' class='toggler  av-title-above '  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-3' data-slide-speed=\"200\" data-title=\"QREN 2015\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: QREN 2015\" data-aria_expanded=\"Click to collapse: QREN 2015\">QREN 2015<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-3' aria-labelledby='toggle-toggle-id-3' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color '  itemprop=\"text\" ><p>Em desenvolvimento<\/p>\n<\/div><\/div><\/div><\/section>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":14,"featured_media":0,"parent":96,"menu_order":98,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-98","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/pages\/98","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/comments?post=98"}],"version-history":[{"count":1,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/pages\/98\/revisions"}],"predecessor-version":[{"id":2764,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/pages\/98\/revisions\/2764"}],"up":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/pages\/96"}],"wp:attachment":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media?parent=98"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}