{"id":92,"date":"2015-10-21T15:08:43","date_gmt":"2015-10-21T15:08:43","guid":{"rendered":"http:\/\/cimbse.pt\/?page_id=92"},"modified":"2015-10-21T15:08:43","modified_gmt":"2015-10-21T15:08:43","slug":"parcerias","status":"publish","type":"page","link":"https:\/\/www.mixlifeweb.com\/cimrbse\/parcerias\/","title":{"rendered":"Parcerias"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_two_third-352b07ef7d3bc99b2e9f92e7a9e06bdb\">\n.flex_column.av-av_two_third-352b07ef7d3bc99b2e9f92e7a9e06bdb{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_two_third-352b07ef7d3bc99b2e9f92e7a9e06bdb av_two_third  avia-builder-el-0  el_before_av_one_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>A <strong>CIM-BSE<\/strong>, pretende ser um parceiro regional, capaz de implementar pr\u00e1ticas de gest\u00e3o que permitam identificar e satisfazer as necessidades dos munic\u00edpios associados e desenvolver estrat\u00e9gias que conduzam a uma maior coes\u00e3o intermunicipal, com resultados na melhoria de qualidade de vida e no desenvolvimento sustentado da regi\u00e3o.<\/p>\n<p>Tem como miss\u00e3o potenciar, promover o desenvolvimento da regi\u00e3o, de otimizar e defender os interesses comuns dos munic\u00edpios associados e refor\u00e7ar a identidade conjunta da regi\u00e3o, mediante a articula\u00e7\u00e3o de interesses e cria\u00e7\u00e3o de sinergias e estimulando o desenvolvimento integrado e coletivo, valorizando parcerias, criando sinergias e maximizando resultados.<\/p>\n<\/div><\/section><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_third-2a64de42b738552fe666ca889af77e28\">\n.flex_column.av-av_one_third-2a64de42b738552fe666ca889af77e28{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_third-2a64de42b738552fe666ca889af77e28 av_one_third  avia-builder-el-2  el_after_av_two_third  el_before_av_one_full  flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_image-edcc997eca81196ad6595d0a53924cad\">\n.avia-image-container.av-av_image-edcc997eca81196ad6595d0a53924cad img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-av_image-edcc997eca81196ad6595d0a53924cad .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-av_image-edcc997eca81196ad6595d0a53924cad av-styling- av-img-linked avia-align-center  avia-builder-el-3  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2015\/10\/parcerias_2x21.png\" data-srcset=\"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2015\/10\/parcerias_2x21.png 336w, https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2015\/10\/parcerias_2x21-291x300.png 291w, https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2015\/10\/parcerias_2x21-36x36.png 36w\" data-sizes=\"(max-width: 336px) 100vw, 336px\" class='avia_image '  aria-label='parcerias_2x2[1]'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-93 avia-img-lazy-loading-not-93 avia_image ' src=\"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2015\/10\/parcerias_2x21.png\" alt='' title='parcerias_2x2[1]'  height=\"346\" width=\"336\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2015\/10\/parcerias_2x21.png 336w, https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2015\/10\/parcerias_2x21-291x300.png 291w, https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2015\/10\/parcerias_2x21-36x36.png 36w\" sizes=\"(max-width: 336px) 100vw, 336px\" \/><\/a><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-352b07ef7d3bc99b2e9f92e7a9e06bdb\">\n.flex_column.av-av_one_full-352b07ef7d3bc99b2e9f92e7a9e06bdb{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-352b07ef7d3bc99b2e9f92e7a9e06bdb av_one_full  avia-builder-el-4  el_after_av_one_third  avia-builder-el-last  first flex_column_div av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-a672a5f046b0ed8eec54a1850058c408\">\n#top .av-special-heading.av-av_heading-a672a5f046b0ed8eec54a1850058c408{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-av_heading-a672a5f046b0ed8eec54a1850058c408 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-a672a5f046b0ed8eec54a1850058c408 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-a672a5f046b0ed8eec54a1850058c408 av-special-heading-h3  avia-builder-el-5  el_before_av_textblock  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Pacto Territorial<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Considerando as orienta\u00e7\u00f5es do Acordo de Parceria, no sentido de se promover uma articula\u00e7\u00e3o entre as interven\u00e7\u00f5es territoriais;<\/p>\n<p>Considerando o \u00e2mbito territorial da Comunidade Intermunicipal das Beiras e Serra da Estrela e das Associa\u00e7\u00f5es de Desenvolvimento Local ADERES \u2013 Associa\u00e7\u00e3o de Desenvolvimento Rural Estrela-Sul, ADRUSE \u2013 Associa\u00e7\u00e3o de Desenvolvimento Rural da Serra da Estrela, Pr\u00f3 Raia \u2013 Associa\u00e7\u00e3o de Desenvolvimento Integrado da Raia Centro Norte, Raia Hist\u00f3rica \u2013 Associa\u00e7\u00e3o de Desenvolvimento do Nordeste da Beira e RUDE \u2013 Associa\u00e7\u00e3o de Desenvolvimento Rural;<\/p>\n<p>Considerando que as organiza\u00e7\u00f5es atr\u00e1s referenciadas t\u00eam por objetivo a promo\u00e7\u00e3o do desenvolvimento sustent\u00e1vel do territ\u00f3rio, \u00e9 estabelecido o presente Pacto Territorial \u201cBeiras e Serra da Estrela \u2013 Estrat\u00e9gias Concertadas\u201d, entre:<\/p>\n<p>Comunidade Intermunicipal das Beiras e Serra da Estrela, com sede no largo Pa\u00e7o Biu 3, 6300-592 Guarda, representada neste ato pelo Presidente do Conselho Executivo, Dr. V\u00edtor Manuel Pinheiro Pereira, adiante designada por CIM BSE;<\/p>\n<p><strong>ADERES<\/strong> \u2013 Associa\u00e7\u00e3o de Desenvolvimento Rural Estrela-Sul, com sede no Largo Nossa Senhora do Carmo 1, 6215-136 Cortes do Meio, representada neste ato pelo Presidente da Dire\u00e7\u00e3o, Dr. Jos\u00e9 Serra dos Reis, adiante designada por ADERES;<\/p>\n<p><strong>ADRUSE<\/strong> \u2013 Associa\u00e7\u00e3o de Desenvolvimento Rural da Serra da Estrela, com sede no Largo Dr. Al\u00edpio de Melo, 6290-520 Gouveia, representada neste ato pelo Presidente do Conselho de Administra\u00e7\u00e3o, Dr. Carlos Filipe Camelo Miranda de Figueiredo, adiante designada por ADRUSE;<\/p>\n<p><strong>Pr\u00f3 Raia<\/strong> \u2013 Associa\u00e7\u00e3o de Desenvolvimento Integrado da Raia Centro Norte, com sede na Rua General P\u00f3voas n.\u00ba 28, 6300-714 Guarda, representada neste ato pelo Presidente da Dire\u00e7\u00e3o, Dr. \u00c1lvaro dos Santos Amaro, adiante designada por Pr\u00f3 Raia;<\/p>\n<p><strong>Raia Hist\u00f3rica<\/strong> \u2013 Associa\u00e7\u00e3o de Desenvolvimento do Nordeste da Beira, com sede na Av. 1.\u00ba de Dezembro 10, 6420-011 Trancoso, representada neste ato pelo Presidente do Conselho de Administra\u00e7\u00e3o, Dr. Am\u00edlcar Jos\u00e9 Nunes Salvador, adiante designada por Raia Hist\u00f3rica;<\/p>\n<p><strong>RUDE<\/strong> \u2013 Associa\u00e7\u00e3o de Desenvolvimento Rural com sede na Rua Conde da Ericeira \u2013 Antiga Casa dos Magistrados, 6200-086 Covilh\u00e3, representada neste ato pelo vogal da Dire\u00e7\u00e3o Dr. Paulo Jorge Canaveira Alves Tourais, adiante designada por RUDE;<\/p>\n<p>O Pacto Territorial \u201cBeiras e Serra da Estrela \u2013 Estrat\u00e9gias Concertadas\u201d visa a articula\u00e7\u00e3o entre o Plano Estrat\u00e9gico de Desenvolvimento Intermunicipal Beiras e Serra da Estrela 2020, da responsabilidade da Comunidade Intermunicipal das Beiras e Serra da Estrela, e as Estrat\u00e9gias de Desenvolvimento Local de Base Comunit\u00e1ria dos Grupos de A\u00e7\u00e3o Local, geridas e dinamizadas pelas Associa\u00e7\u00f5es de Desenvolvimento Local anteriormente referidas, e que se rege pelas cl\u00e1usulas seguintes:<\/p>\n<p style=\"text-align: center;\"><strong>Cl\u00e1usula 1.\u00aa<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>\u00c2mbito territorial<\/strong><\/p>\n<p>1. O Pacto Territorial \u201cBeiras e Serra da Estrela \u2013 Estrat\u00e9gias Concertadas\u201d abrange os munic\u00edpios que integram a Comunidade Intermunicipal das Beiras e Serra da Estrela e \u00e1rea de atua\u00e7\u00e3o das Associa\u00e7\u00f5es de Desenvolvimento Local ADERES, ADRUSE, Pr\u00f3 Raia, Raia Hist\u00f3rica e RUDE, a saber:<\/p>\n<p>Almeida,Belmonte, Celorico da Beira, Covilh\u00e3, Figueira de Castelo Rodrigo, Fornos de Algodres, Fund\u00e3o, Gouveia, Guarda, Manteigas, M\u00eada, Pinhel, Sabugal, Seia e Trancoso;<\/p>\n<p style=\"text-align: center;\"><strong>Cl\u00e1usula 2.\u00aa<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>\u00c2mbito tem\u00e1tico<\/strong><\/p>\n<p>1. Pretende-se estabelecer uma linha de trabalho entre as partes signat\u00e1rias do presente Pacto Territorial, em \u00e1reas tem\u00e1ticas contempladas no Plano Estrat\u00e9gico de Desenvolvimento Intermunicipal, e que poder\u00e3o ser comuns \u00e0s Estrat\u00e9gias de Desenvolvimento Local de Base Comunit\u00e1ria, nomeadamente:<\/p>\n<p>a) Inova\u00e7\u00e3o, internacionaliza\u00e7\u00e3o e atra\u00e7\u00e3o de investimento produtivo;<\/p>\n<p>b) Turismo e agro-ind\u00fastria;<\/p>\n<p>c) Log\u00edstica, mobilidade e servi\u00e7os b\u00e1sicos;<\/p>\n<p>d) Capital humano e moderniza\u00e7\u00e3o administrativa;<\/p>\n<p>e) Sa\u00fade, terceiro sector e desenvolvimento social.<\/p>\n<p style=\"text-align: center;\"><strong>Cl\u00e1usula 3.\u00aa<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Articula\u00e7\u00e3o das Interven\u00e7\u00f5es<\/strong><\/p>\n<p>1. Os Planos de A\u00e7\u00e3o da Comunidade Intermunicipal das Beiras e Serra da Estrela e as Estrat\u00e9gias de Desenvolvimento Comunit\u00e1rio de Base Local das ADL signat\u00e1rias deste Pacto Territorial dever\u00e3o ser articuladas, para que n\u00e3o existam interven\u00e7\u00f5es sobrepostas, e que se canalizem esfor\u00e7os no sentido de operacionalizar interven\u00e7\u00f5es comuns, como s\u00e3o exemplo a participa\u00e7\u00e3o conjunta em feiras, a realiza\u00e7\u00e3o de eventos de caracter intermunicipal, a promo\u00e7\u00e3o de uma cultura empreendedora no territ\u00f3rio, entre outras iniciativas.<\/p>\n<p style=\"text-align: center;\"><strong>Cl\u00e1usula 4.\u00aa<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Governan\u00e7a<\/strong><\/p>\n<p>1. O modelo de governa\u00e7\u00e3o para a prossecu\u00e7\u00e3o do presente Pacto Territorial assenta na articula\u00e7\u00e3o concertada da atua\u00e7\u00e3o das partes signat\u00e1rias, nomeadamente ao n\u00edvel de:<\/p>\n<p>a) Programa\u00e7\u00e3o articulada das atividades anuais, identificando para o efeito a interven\u00e7\u00e3o de cada organiza\u00e7\u00e3o e aloca\u00e7\u00e3o de recursos;<\/p>\n<p>b) Monitoriza\u00e7\u00e3o conjunta, da execu\u00e7\u00e3o do plano de a\u00e7\u00e3o, de forma a introduzir os ajustes e revis\u00f5es que se considerem necess\u00e1rios.<\/p>\n<p>2. Para al\u00e9m das Associa\u00e7\u00f5es de Desenvolvimento Local integrarem o Conselho Consultivo, dever\u00e1 ser constitu\u00eddo um N\u00facleo Executivo, constitu\u00eddo pelas partes signat\u00e1rias, que re\u00fana trimestralmente, por forma a operacionalizar as quest\u00f5es evidenciadas no ponto anterior.<\/p>\n<p>3. A CIM BSE participar\u00e1 nos \u00d3rg\u00e3os de Gest\u00e3o dos GAL a constituir no territ\u00f3rio.<\/p>\n<p style=\"text-align: center;\"><strong>Cl\u00e1usula 5.\u00aa<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Vig\u00eancia<\/strong><\/p>\n<p>1. O Pacto Territorial \u201cBeiras e Serra da Estrela \u2013 Estrat\u00e9gias Concertadas\u201d vincula todas as organiza\u00e7\u00f5es signat\u00e1rias e entra em vigor na data da sua assinatura.<\/p>\n<p>2. O Pacto Territorial \u201cBeiras e Serra da Estrela \u2013 Estrat\u00e9gias Concertadas\u201d pode vir a ser modificado, no todo ou em parte por acordo entre as partes.<\/p>\n<p>O presente Pacto Territorial \u201cBeiras e Serra da Estrela \u2013 Estrat\u00e9gias Concertadas\u201d, \u00e9 elaborado em seis vias, cont\u00e9m cinco p\u00e1ginas e ser\u00e1 rubricado e assinado pelas partes signat\u00e1rias.<\/p>\n<p><strong>Guarda; 10 de fevereiro de 2015.<\/strong><\/p>\n<p>Comunidade Intermunicipal das Beiras e Serra da Estrela<\/p>\n<p>(Dr. V\u00edtor Manuel Pinheiro Pereira)<\/p>\n<p>ADERES \u2013 Associa\u00e7\u00e3o de Desenvolvimento Rural Estrela-Sul<\/p>\n<p>(Dr. Jos\u00e9 Serra dos Reis)<\/p>\n<p>ADRUSE \u2013 Associa\u00e7\u00e3o de Desenvolvimento Rural da Serra da Estrela<\/p>\n<p>(Dr. Carlos Filipe Camelo Miranda de Figueiredo)<\/p>\n<p>Pr\u00f3 Raia \u2013 Associa\u00e7\u00e3o de Desenvolvimento Integrado da Raia Centro Norte<\/p>\n<p>(Dr. \u00c1lvaro dos Santos Amaro)<\/p>\n<p>Raia Hist\u00f3rica \u2013 Associa\u00e7\u00e3o de Desenvolvimento do Nordeste da Beira<\/p>\n<p>(Dr. Am\u00edlcar Jos\u00e9 Nunes Salvador)<\/p>\n<p>RUDE \u2013 Associa\u00e7\u00e3o de Desenvolvimento Rural<\/p>\n<p>(Dr. Paulo Jorge Canaveira Alves Tourais)<\/p>\n<\/div><\/section><\/p><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":14,"featured_media":0,"parent":0,"menu_order":94,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-92","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/pages\/92","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/comments?post=92"}],"version-history":[{"count":1,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/pages\/92\/revisions"}],"predecessor-version":[{"id":5748,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/pages\/92\/revisions\/5748"}],"wp:attachment":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media?parent=92"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}