{"id":149,"date":"2015-10-21T16:28:29","date_gmt":"2015-10-21T16:28:29","guid":{"rendered":"http:\/\/cimbse.pt\/?page_id=149"},"modified":"2015-10-21T16:28:29","modified_gmt":"2015-10-21T16:28:29","slug":"celorico-da-beira","status":"publish","type":"page","link":"https:\/\/www.mixlifeweb.com\/cimrbse\/apresentacao\/municipios-associados\/celorico-da-beira\/","title":{"rendered":"Celorico da Beira"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_third-352b07ef7d3bc99b2e9f92e7a9e06bdb\">\n.flex_column.av-av_one_third-352b07ef7d3bc99b2e9f92e7a9e06bdb{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_third-352b07ef7d3bc99b2e9f92e7a9e06bdb av_one_third  avia-builder-el-0  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_image-f68d910f90c2fff9b24a07e2dc5ee14d\">\n.avia-image-container.av-av_image-f68d910f90c2fff9b24a07e2dc5ee14d img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-av_image-f68d910f90c2fff9b24a07e2dc5ee14d .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-av_image-f68d910f90c2fff9b24a07e2dc5ee14d av-styling- avia-align-center  avia-builder-el-1  el_before_av_textblock  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-123 avia-img-lazy-loading-not-123 avia_image ' src=\"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2015\/10\/celorico.png\" alt='' title='celorico'  height=\"434\" width=\"413\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2015\/10\/celorico.png 413w, https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2015\/10\/celorico-285x300.png 285w\" sizes=\"(max-width: 413px) 100vw, 413px\" \/><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p style=\"text-align: center;\"><a href=\"http:\/\/www.cm-celoricodabeira.pt\/\" target=\"_blank\">www.cm-celoricodabeira.pt<\/a><\/p>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_two_third-2a64de42b738552fe666ca889af77e28\">\n.flex_column.av-av_two_third-2a64de42b738552fe666ca889af77e28{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_two_third-2a64de42b738552fe666ca889af77e28 av_two_third  avia-builder-el-3  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Situado no maci\u00e7o montanhoso da Serra da Estrela, possui quase 50% da sua \u00e1rea integrada no Parque Natural Serra da Estrela. A vila de Celorico da Beira, encontra-se localizada a cerca de\u00a0 500 m de altitude, atingindo o concelho o seu ponto mais alto na freguesia de Prados com 1260m. Administrativamente, localiza-se no Distrito da Guarda e \u00e9 ladeado a Nascente pelo concelho da Guarda, a Poente por Fornos de Algodres, a Sul por Gouveia e Norte por Trancoso. Encontra-se abrangido na NUT II (Centro) e NUT III (Beira Interior Norte).<\/p>\n<p>Bem localizado em termos de acessibilidade, nomeadamente atrav\u00e9s da A25, que liga Aveiro \u00e0 fronteira de Espanha. Futuramente ir\u00e1 ter tamb\u00e9m o IP2, que far\u00e1 liga\u00e7\u00e3o do Norte ao Sul do Pa\u00eds pelo Interior.<\/p>\n<p>A EN 102 faz a liga\u00e7\u00e3o com o concelho de Trancoso, enquanto a EN 16 liga o concelho de Celorico ao de Fornos de Algodres e Guarda, tal como a EN 17 liga Celorico a Gouveia.<\/p>\n<p>\u00c9 servido ainda pela Linha Ferrovi\u00e1ria da Beira Alta<\/p>\n<p>\u00c9 constitu\u00eddo por 16 freguesias, que no seu total abrangem uma \u00e1rea de 24 722 ha. A maior freguesia do concelho \u00e9 Fornotelheiro, com 2076,32 ha, contrastando com Corti\u00e7\u00f4 da Serra, com 478,75 ha.<\/p>\n<p>Hipsometricamente, o concelho divide-se em duas partes. Uma, a sul do Rio Mondego, com altitudes que v\u00e3o diminuindo progressivamente dos 1260 aos 360 metros, nos sentidos sul-norte e sudeste-noroeste com pequenos vales recortados por linhas de \u00e1gua. A outra, a norte, \u00e9 uma zona quase plana, com as m\u00e1ximas altitudes j\u00e1 na fronteira nordeste do concelho.Os maiores declives situam-se, de uma maneira geral, no quadrante Sudeste do concelho. Devido \u00e0\u00a0 sua morfologia, apresenta uma grande variedade em termos de exposi\u00e7\u00e3o\u00a0 solar das suas encostas.<\/p>\n<p>Al\u00e9m do Mondego, que atravessa o Concelho na direc\u00e7\u00e3o E-W, fazendo uma grande curva com um percurso de 19.000 metros e um declive de 0,4%, a norte existem alguns recursos de regime e at\u00e9 de caudal significativo, como sejam a Ribeira da Velosa, Ribeira dos Tamanhos e a Ribeira da Quinta das Seixas. A sul deste rio destacamos a Ribeira da Cabe\u00e7a Alta, Ribeira de Salgueirais, Ribeira de Linhares e a Ribeira do Rebolal que constituem importante recurso h\u00eddrico dessa zona do concelho.<\/p>\n<p>Existem ainda in\u00fameros outros ribeiros, regatos e mesmo algumas linhas de \u00e1gua que se distribuem por toda a zona, tendo contudo um regime tempor\u00e1rio, pelo que nas alturas de seca e nos meses de Ver\u00e3o, regra geral, n\u00e3o possuem qualquer caudal.<\/p>\n<p>O\u00a0 clima do concelho, segundo a classifica\u00e7\u00e3o de Koppen, \u00e9 do Tipo CSB \u2013 clima temperado, com Invernos chuvosos e Ver\u00e3o seco e pouco quente.<\/p>\n<\/div><\/section><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":14,"featured_media":0,"parent":120,"menu_order":77,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-149","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/pages\/149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/comments?post=149"}],"version-history":[{"count":0,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/pages\/149\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/pages\/120"}],"wp:attachment":[{"href":"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media?parent=149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}